{"id":26632,"date":"2022-12-25T23:26:01","date_gmt":"2022-12-25T23:26:01","guid":{"rendered":"https:\/\/ecloud.solutions\/?page_id=26632"},"modified":"2023-03-11T17:51:19","modified_gmt":"2023-03-11T17:51:19","slug":"ehrm","status":"publish","type":"page","link":"https:\/\/ecloud.solutions\/es\/ehrm\/","title":{"rendered":"eHRM"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"26632\" class=\"elementor elementor-26632\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8226b96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8226b96\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d788f5 layouts-column-align-inherit layouts-section-position-none\" data-id=\"0d788f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-ad72468 elementor-widget elementor-widget-spacer\" data-id=\"ad72468\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4cadf1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4cadf1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-8c54760 layouts-column-align-inherit layouts-section-position-none\" data-id=\"8c54760\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-d299907 elementor-widget elementor-widget-spacer\" data-id=\"d299907\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-3f94799 elementor-widget elementor-widget-heading\" data-id=\"3f94799\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">e-hRM<br>Gesti\u00f3n de Recursos Humanos por eCloud<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ef24ae9 layouts-column-align-inherit layouts-section-position-none\" data-id=\"ef24ae9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-2d7f0aa elementor-widget elementor-widget-image\" data-id=\"2d7f0aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"245\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/eHR.png?fit=300%2C245&amp;ssl=1\" class=\"attachment-medium size-medium wp-image-26625\" alt=\"eHRM - Human Resource Management\" srcset=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/eHR.png?w=415&amp;ssl=1 415w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/eHR.png?resize=300%2C245&amp;ssl=1 300w\" sizes=\"auto, (min-width: 960px) 75vw, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-79d7588 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79d7588\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-437e4b2 layouts-column-align-inherit layouts-section-position-none\" data-id=\"437e4b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-7a6b868 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a6b868\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-16cc085 layouts-column-align-inherit layouts-section-position-none\" data-id=\"16cc085\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-26c5ca9 elementor-widget elementor-widget-section_title\" data-id=\"26c5ca9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"center iq-title-box iq-title-default iq-title-box-1\">\n\t\t<div class=\"iq-title-icon\">\n\t\t\t\t\t<\/div>\n\t\t\t<span class=\"iq-subtitle iq-title-box-1\">how we can help?<\/span>\t\t<h2 class=\"iq-title\" >\n\t\t\tuna soluci\u00f3n completa para la gesti\u00f3n eficaz de su personal.\t\t<\/h2>\n\t\t\t<p class=\"iq-title-desc\">Una soluci\u00f3n en la nube que le permite tener todo en un solo lugar desde cualquier lugar.<\/p>\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-5e3c8682 elementor-widget elementor-widget-iqonic_Tabs\" data-id=\"5e3c8682\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_Tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n    <div class=\"iq-tabs iq-tab-vertical-3\">\n        <div class=\"row align-items-center\">\n            <div class=\"col-lg-4\">\n                <ul class=\"nav nav-pills\" id=\"pills-tab\" role=\"tablist\">\n                    \n    <li class=\"nav-item\">\n        <a class=\"nav-link active\" data-toggle=\"pill\" href=\"#tabs-077\" role=\"tab\">\n            <div class=\"media\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/service-5.png?ssl=1\" title=\"servicio-5\" alt=\"image\" loading=\"lazy\" \/>\n                    <div class=\"media-body\">\n                        <h6 class=\"tab-title\">Web Responsive<\/h6><p class=\"mb-0 tab-title-desc\">Work from any device<\/p>\n                    <\/div>\n            <\/div>\n        <\/a>\n    <\/li>\n    <li class=\"nav-item\">\n        <a class=\"nav-link\" data-toggle=\"pill\" href=\"#tabs-177\" role=\"tab\">\n            <div class=\"media\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/service-4.png?ssl=1\" title=\"servicio-4\" alt=\"image\" loading=\"lazy\" \/>\n                    <div class=\"media-body\">\n                        <h6 class=\"tab-title\">Employee Dashboard<\/h6><p class=\"mb-0 tab-title-desc\">Check his\/her CV, Docs, skills, contract, among others.<\/p>\n                    <\/div>\n            <\/div>\n        <\/a>\n    <\/li>\n    <li class=\"nav-item\">\n        <a class=\"nav-link\" data-toggle=\"pill\" href=\"#tabs-277\" role=\"tab\">\n            <div class=\"media\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/service-3.png?ssl=1\" title=\"servicio-3\" alt=\"image\" loading=\"lazy\" \/>\n                    <div class=\"media-body\">\n                        <h6 class=\"tab-title\">Timesheet<\/h6><p class=\"mb-0 tab-title-desc\">Manage your activities &amp; workforce Keep your projects under control and manage employee time.<\/p>\n                    <\/div>\n            <\/div>\n        <\/a>\n    <\/li>\n    <li class=\"nav-item\">\n        <a class=\"nav-link\" data-toggle=\"pill\" href=\"#tabs-377\" role=\"tab\">\n            <div class=\"media\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/service-2.png?ssl=1\" title=\"servicio-2\" alt=\"image\" loading=\"lazy\" \/>\n                    <div class=\"media-body\">\n                        <h6 class=\"tab-title\">Recruitment Process<\/h6><p class=\"mb-0 tab-title-desc\">Hiring Processes Made Easy From sourcing to contract, handle your recruitment process easily.<\/p>\n                    <\/div>\n            <\/div>\n        <\/a>\n    <\/li>                <\/ul>\n            <\/div>\n            <div class=\"col-lg-8\">\n                <div class=\"tab-content\">\n                    \n    <div class=\"tab-pane active\" id=\"tabs-077\" role=\"tabpanel\">\n        <div><p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignnone wp-image-26646 size-full\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/responsive-image-2.png?resize=762%2C507&#038;ssl=1\" alt=\"\" width=\"762\" height=\"507\" srcset=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/responsive-image-2.png?w=762&amp;ssl=1 762w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/responsive-image-2.png?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/responsive-image-2.png?resize=720%2C480&amp;ssl=1 720w\" sizes=\"auto, (min-width: 960px) 75vw, 100vw\" \/><\/p><\/div>\n    <\/div>\n    <div class=\"tab-pane\" id=\"tabs-177\" role=\"tabpanel\">\n        <div><p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignnone wp-image-26650 size-full\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/employee-dashboard.png?resize=1242%2C883&#038;ssl=1\" alt=\"\" width=\"1242\" height=\"883\" srcset=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/employee-dashboard.png?w=1242&amp;ssl=1 1242w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/employee-dashboard.png?resize=300%2C213&amp;ssl=1 300w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/employee-dashboard.png?resize=1024%2C728&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/employee-dashboard.png?resize=768%2C546&amp;ssl=1 768w\" sizes=\"auto, (min-width: 960px) 75vw, 100vw\" \/><\/p><\/div>\n    <\/div>\n    <div class=\"tab-pane\" id=\"tabs-277\" role=\"tabpanel\">\n        <div><p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignnone wp-image-26654 size-full\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/timesheet.png?resize=1913%2C887&#038;ssl=1\" alt=\"\" width=\"1913\" height=\"887\" srcset=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/timesheet.png?w=1913&amp;ssl=1 1913w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/timesheet.png?resize=300%2C139&amp;ssl=1 300w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/timesheet.png?resize=1024%2C475&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/timesheet.png?resize=768%2C356&amp;ssl=1 768w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/timesheet.png?resize=1536%2C712&amp;ssl=1 1536w\" sizes=\"auto, (min-width: 960px) 75vw, 100vw\" \/><\/p><\/div>\n    <\/div>\n    <div class=\"tab-pane\" id=\"tabs-377\" role=\"tabpanel\">\n        <div><p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignnone wp-image-26658 size-full\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/recruitment.png?resize=1917%2C891&#038;ssl=1\" alt=\"\" width=\"1917\" height=\"891\" srcset=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/recruitment.png?w=1917&amp;ssl=1 1917w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/recruitment.png?resize=300%2C139&amp;ssl=1 300w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/recruitment.png?resize=1024%2C476&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/recruitment.png?resize=768%2C357&amp;ssl=1 768w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/recruitment.png?resize=1536%2C714&amp;ssl=1 1536w\" sizes=\"auto, (min-width: 960px) 75vw, 100vw\" \/><\/p><\/div>\n    <\/div>                <\/div>\n            <\/div>\n        <\/div>\n    <\/div> \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-1498aba elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1498aba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57d386d layouts-column-align-inherit layouts-section-position-none\" data-id=\"57d386d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-e99dcf5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e99dcf5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0b34416 layouts-column-align-inherit layouts-section-position-none\" data-id=\"0b34416\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-5fe2797 elementor-widget elementor-widget-iqonic_process_steps\" data-id=\"5fe2797\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_process_steps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"iq-process iq-process-step-style-9  iq-box-shadow\">   \n        <div class=\"iq-process-step\">\n           \n            <div class=\"iq-step-content\">\n                   <img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" class=\"hover-img\" src=\"https:\/\/i0.wp.com\/wordpress.iqonic.design\/product\/wp\/qloud\/wp-content\/uploads\/2022\/05\/Group-5.png?ssl=1\" alt=\"fancybox\">                    <div class=\"step-number-wrapper\">\n                        <span class=\"step-number\" >Advantage 01<\/span>\n                    <\/div>\n                                <\/div>\n                    \n            <div class=\"iq-step-text-area\">\n                \n                                    <h5 class=\"iq-step-title\">Software as a Service - SaaS<\/h5>\n                                    <p class=\"iq-step-desc\">Access from anywhere whenever and wherever you want, without investment in hardware or technological obsolescence.<\/p> \n                     <div class=\"iq-btn-container\" >\n\n     <a class=\"iq-button-animated linked-btn has-icon btn-icon-right\" href=\"https:\/\/ecloud.solutions\/es\/about-us-1\/\" >  \n          \n                <span class=\"btn_text-main\"> \n                    <span class=\"btn_text one\">Leer m\u00e1s <\/span>\n                    <span class=\"btn_text two\">Leer m\u00e1s <\/span>\n                <\/span>                 <span class=\"btn-icon\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"10px\" height=\"10px\" viewbox=\"0 0 10 10\" enable-background=\"new 0 0 10 10\" xml:space=\"preserve\"><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"6.052\" y1=\"3.933\" x2=\"0.953\" y2=\"9.031\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"2.312\" y1=\"1.241\" x2=\"9.313\" y2=\"1.241\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"8.609\" y1=\"0.501\" x2=\"8.609\" y2=\"7.5\"><\/line><\/svg>\n                <\/span> \n                 \n\n    <\/a>\n<\/div>\n                \n            <\/div>\n        <\/div>\n\n    <\/div>\n   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-92f9978 layouts-column-align-inherit layouts-section-position-none\" data-id=\"92f9978\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-95d62eb elementor-widget elementor-widget-iqonic_process_steps\" data-id=\"95d62eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_process_steps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"iq-process iq-process-step-style-9  iq-box-shadow\">   \n        <div class=\"iq-process-step\">\n           \n            <div class=\"iq-step-content\">\n                   <img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" class=\"hover-img\" src=\"https:\/\/i0.wp.com\/wordpress.iqonic.design\/product\/wp\/qloud\/wp-content\/uploads\/2022\/05\/Group-8.png?ssl=1\" alt=\"fancybox\">                    <div class=\"step-number-wrapper\">\n                        <span class=\"step-number\" >Advantage 02<\/span>\n                    <\/div>\n                                <\/div>\n                    \n            <div class=\"iq-step-text-area\">\n                \n                                    <h5 class=\"iq-step-title\">Focus on your business<\/h5>\n                                    <p class=\"iq-step-desc\">We take care of guaranteeing, maintaining and updating the hardware and software infrastructure of the solution<\/p> \n                     <div class=\"iq-btn-container\" >\n\n     <a class=\"iq-button-animated linked-btn has-icon btn-icon-right\" href=\"https:\/\/ecloud.solutions\/es\/about-us-1\/\" >  \n          \n                <span class=\"btn_text-main\"> \n                    <span class=\"btn_text one\">Leer m\u00e1s <\/span>\n                    <span class=\"btn_text two\">Leer m\u00e1s <\/span>\n                <\/span>                 <span class=\"btn-icon\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"10px\" height=\"10px\" viewbox=\"0 0 10 10\" enable-background=\"new 0 0 10 10\" xml:space=\"preserve\"><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"6.052\" y1=\"3.933\" x2=\"0.953\" y2=\"9.031\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"2.312\" y1=\"1.241\" x2=\"9.313\" y2=\"1.241\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"8.609\" y1=\"0.501\" x2=\"8.609\" y2=\"7.5\"><\/line><\/svg>\n                <\/span> \n                 \n\n    <\/a>\n<\/div>\n                \n            <\/div>\n        <\/div>\n\n    <\/div>\n   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c1633f8 layouts-column-align-inherit layouts-section-position-none\" data-id=\"c1633f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-09952ab elementor-widget elementor-widget-iqonic_process_steps\" data-id=\"09952ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_process_steps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"iq-process iq-process-step-style-9  iq-box-shadow\">   \n        <div class=\"iq-process-step\">\n           \n            <div class=\"iq-step-content\">\n                   <img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" class=\"hover-img\" src=\"https:\/\/i0.wp.com\/wordpress.iqonic.design\/product\/wp\/qloud\/wp-content\/uploads\/2022\/06\/3.png?ssl=1\" alt=\"fancybox\">                    <div class=\"step-number-wrapper\">\n                        <span class=\"step-number\" >Advantage 03<\/span>\n                    <\/div>\n                                <\/div>\n                    \n            <div class=\"iq-step-text-area\">\n                \n                                    <h5 class=\"iq-step-title\">Grow to suit you<\/h5>\n                                    <p class=\"iq-step-desc\">You don&#039;t have to buy a super expensive license to get started, just pay as you go based on the size of your organization<\/p> \n                     <div class=\"iq-btn-container\" >\n\n     <a class=\"iq-button-animated linked-btn has-icon btn-icon-right\" href=\"https:\/\/ecloud.solutions\/es\/about-us-1\/\" >  \n          \n                <span class=\"btn_text-main\"> \n                    <span class=\"btn_text one\">Leer m\u00e1s <\/span>\n                    <span class=\"btn_text two\">Leer m\u00e1s <\/span>\n                <\/span>                 <span class=\"btn-icon\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"10px\" height=\"10px\" viewbox=\"0 0 10 10\" enable-background=\"new 0 0 10 10\" xml:space=\"preserve\"><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"6.052\" y1=\"3.933\" x2=\"0.953\" y2=\"9.031\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"2.312\" y1=\"1.241\" x2=\"9.313\" y2=\"1.241\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"8.609\" y1=\"0.501\" x2=\"8.609\" y2=\"7.5\"><\/line><\/svg>\n                <\/span> \n                 \n\n    <\/a>\n<\/div>\n                \n            <\/div>\n        <\/div>\n\n    <\/div>\n   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-705746b6 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"705746b6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-70a3d7d3 layouts-column-align-inherit layouts-section-position-none\" data-id=\"70a3d7d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-ea2feab elementor-widget elementor-widget-image\" data-id=\"ea2feab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/06\/Group-34805.webp?fit=637%2C562&amp;ssl=1\" title=\"Grupo-34805\" alt=\"image\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a2e8b9d layouts-column-align-inherit layouts-section-position-none elementor-invisible\" data-id=\"a2e8b9d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-7484f66 elementor-widget elementor-widget-section_title\" data-id=\"7484f66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"text-left iq-title-box iq-title-default iq-title-box-1\">\n\t\t<div class=\"iq-title-icon\">\n\t\t\t\t\t<\/div>\n\t\t\t<span class=\"iq-subtitle iq-title-box-1\">About us<\/span>\t\t<h2 class=\"iq-title\" >\n\t\t\tSomos m\u00e1s que una empresa de soluciones en la nube\t\t<\/h2>\n\t\t\t<p class=\"iq-title-desc\">Nos enfocamos en identificar aquellos puntos de mejora y crecimiento de su empresa basados en a\u00f1os de experiencia en consultor\u00eda, esto nos permite tener la confianza para ofrecerle nuestras soluciones o sugerirle otras soluciones fuera de nuestro portafolio, buscando siempre la satisfacci\u00f3n de nuestros clientes.<\/p>\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b1a7a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b1a7a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-363f514 layouts-column-align-inherit layouts-section-position-none\" data-id=\"363f514\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-90a0a71 elementor-widget elementor-widget-iqonic_counter\" data-id=\"90a0a71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"iq-counter  iq-counter-style-1\">\n\t\t\t\n\t\t\t<div class=\"counter-content\">\n\t\t\t\t<p class=\"iq-counter-info\">\n\t\t\t\t\t\t\t\t\t<span class=\"timer\"  data-to=\"70\" data-speed=\"5000\">\n\t\t\t\t\t    70\t\t\t\t    <\/span>\n                     \t\t\t\n\t\t\t\t<span class=\"counter-after-content\"><\/span>\n\t\t\t\t<span class=\"counter-symbol\">%<\/span><\/p>\n\t\t\t\t    \t\t\t\t\t<p class=\"counter-content-text\">Customer retention<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t     \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4b023b5 layouts-column-align-inherit layouts-section-position-none\" data-id=\"4b023b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-d423dce elementor-widget elementor-widget-iqonic_counter\" data-id=\"d423dce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"iq-counter  iq-counter-style-1\">\n\t\t\t\n\t\t\t<div class=\"counter-content\">\n\t\t\t\t<p class=\"iq-counter-info\">\n\t\t\t\t\t\t\t\t\t<span class=\"timer\"  data-to=\"22\" data-speed=\"5000\">\n\t\t\t\t\t    22\t\t\t\t    <\/span>\n                     \t\t\t\n\t\t\t\t<span class=\"counter-after-content\"><\/span>\n\t\t\t\t<span class=\"counter-symbol\">%<\/span><\/p>\n\t\t\t\t    \t\t\t\t\t<p class=\"counter-content-text\">Annual growth<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t     \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-401096a4 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"401096a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61fbb2db layouts-column-align-inherit layouts-section-position-none\" data-id=\"61fbb2db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-1aff709d elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1aff709d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5a57cc42 layouts-column-align-inherit layouts-section-position-none\" data-id=\"5a57cc42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-62354913 elementor-widget elementor-widget-section_title\" data-id=\"62354913\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"center iq-title-box iq-title-default iq-title-box-1\">\n\t\t<div class=\"iq-title-icon\">\n\t\t\t\t\t<\/div>\n\t\t\t<span class=\"iq-subtitle iq-title-box-1\">Our Services<\/span>\t\t<h2 class=\"iq-title\" >\n\t\t\tPanel de control y API potentes\t\t<\/h2>\n\t\t\t\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-60374003 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"60374003\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-28419462 layouts-column-align-inherit layouts-section-position-none\" data-id=\"28419462\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-3bacb43c elementor-widget elementor-widget-section_title\" data-id=\"3bacb43c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"center iq-title-box iq-title-default iq-title-box-1\">\n\t\t<div class=\"iq-title-icon\">\n\t\t\t\t\t<\/div>\n\t\t\t<span class=\"iq-subtitle iq-title-box-1\">pricing plans<\/span>\t\t<h2 class=\"iq-title\" >\n\t\t\tNuestros poderosos planes de precios mensuales\t\t<\/h2>\n\t\t\t\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8c000d elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8c000d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e265a79 layouts-column-align-inherit layouts-section-position-none elementor-invisible\" data-id=\"e265a79\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-4afee7c elementor-widget elementor-widget-iqonic_price\" data-id=\"4afee7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n    <div  class=\"iq-price-container iq-price-table-4  text-center iq-box-shadow\">\n        <div class=\"iq-price-header\">  \n\n            <span class=\"iq-price-label\">reloj electronico<\/span>\n\n            <p class=\"iq-price-description\">Sistema de Control de Asistencia<\/p> \n         \n        <\/div>\n\n        <div class=\"sub-header-main\">\n            \n            <div class=\"iq-price-sub-header\">\n                <h4 class=\"iq-price\">\n                    <small>&#36;<\/small>5                    <span class=\"iq-price-desc\">USD\/User                    <\/span>\n                <\/h4>\n                                    <p><p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignnone size-medium wp-image-26748\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2023\/01\/ECLOCKv2.png?resize=300%2C216&#038;ssl=1\" alt=\"\" width=\"300\" height=\"216\" srcset=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2023\/01\/ECLOCKv2.png?w=409&amp;ssl=1 409w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2023\/01\/ECLOCKv2.png?resize=300%2C216&amp;ssl=1 300w\" sizes=\"auto, (min-width: 960px) 75vw, 100vw\" \/>Sistema de Control de Asistencia<\/p><\/p>\n                            <\/div>\n            \n        <\/div>\n\n        <div class=\"iq-price-body\">\n            <ul class=\"iq-price-service\">\n                                       <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Dashboard<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Employee Database<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>HR Administration<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Attendance &amp; Leaves<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>                        <span>Face Recognition<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>                        <span>Geo fencing restriction<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Project Management<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Timeesheet<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Multi-Company<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>HR Reports<\/span> \n                    <\/li>\n                      \n            <\/ul>\n        <\/div>\n\n        <div class=\"iq-price-footer\">\n             <div class=\"iq-btn-container\" >\n\n     <a class=\"iq-button-animated has-icon btn-icon-right\" href=\"https:\/\/ecloud.solutions\/es\/ehrm\/\" >  \n          \n                <span class=\"btn_text-main\"> \n                    <span class=\"btn_text one\">Purchase Now <\/span>\n                    <span class=\"btn_text two\">Purchase Now <\/span>\n                <\/span>                 <span class=\"btn-icon\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"10px\" height=\"10px\" viewbox=\"0 0 10 10\" enable-background=\"new 0 0 10 10\" xml:space=\"preserve\"><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"6.052\" y1=\"3.933\" x2=\"0.953\" y2=\"9.031\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"2.312\" y1=\"1.241\" x2=\"9.313\" y2=\"1.241\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"8.609\" y1=\"0.501\" x2=\"8.609\" y2=\"7.5\"><\/line><\/svg>\n                <\/span> \n                 \n\n    <\/a>\n<\/div>\n        <\/div>\n    <\/div>\n\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0bd86b3 layouts-column-align-inherit layouts-section-position-none elementor-invisible\" data-id=\"0bd86b3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-894aa8b elementor-widget elementor-widget-iqonic_price\" data-id=\"894aa8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n    <div  class=\"iq-price-container iq-price-table-4  text-center iq-box-shadow iq-box-shadow\">\n        <div class=\"iq-price-header\">  \n\n            <span class=\"iq-price-label\">e-HRM<\/span>\n\n            <p class=\"iq-price-description\">Sistema de Gesti\u00f3n de Recursos Humanos<\/p> \n         \n        <\/div>\n\n        <div class=\"sub-header-main\">\n            \n            <div class=\"iq-price-sub-header\">\n                <h4 class=\"iq-price\">\n                    <small>&#36;<\/small>12                    <span class=\"iq-price-desc\">USD\/User                    <\/span>\n                <\/h4>\n                                    <p><p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignnone size-medium wp-image-26625\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/eHR.png?resize=300%2C245&#038;ssl=1\" alt=\"eHRM - Human Resource Management\" width=\"300\" height=\"245\" srcset=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/eHR.png?w=415&amp;ssl=1 415w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/eHR.png?resize=300%2C245&amp;ssl=1 300w\" sizes=\"auto, (min-width: 960px) 75vw, 100vw\" \/><\/p><\/p>\n                            <\/div>\n            \n        <\/div>\n\n        <div class=\"iq-price-body\">\n            <ul class=\"iq-price-service\">\n                                       <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Dashboard<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Employee Database<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>HR Administration<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Attendance &amp; Leaves<\/span> \n                    <\/li>\n                                         <li class=\"inactive\">\n                          <i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>                        <span>Face Recognition<\/span> \n                    <\/li>\n                                         <li class=\"inactive\">\n                          <i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>                        <span>Geo rencing restriction<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Project Management<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Timeesheet<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Multi-Company<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>HR Reports<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Payroll<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Appraisal<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Recruitment<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Custody<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Disciplinary Tracking<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>HR Reminder<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Legal Action<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Employee Checklist<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Resignation<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Employee Survey<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Gesti\u00f3n de vacaciones<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Anuncios de recursos humanos<\/span> \n                    <\/li>\n                      \n            <\/ul>\n        <\/div>\n\n        <div class=\"iq-price-footer\">\n             <div class=\"iq-btn-container\" >\n\n     <a class=\"iq-button-animated has-icon btn-icon-right\" href=\"https:\/\/ecloud.solutions\/es\/ehrm\/\" >  \n          \n                <span class=\"btn_text-main\"> \n                    <span class=\"btn_text one\">Purchase Now <\/span>\n                    <span class=\"btn_text two\">Purchase Now <\/span>\n                <\/span>                 <span class=\"btn-icon\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"10px\" height=\"10px\" viewbox=\"0 0 10 10\" enable-background=\"new 0 0 10 10\" xml:space=\"preserve\"><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"6.052\" y1=\"3.933\" x2=\"0.953\" y2=\"9.031\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"2.312\" y1=\"1.241\" x2=\"9.313\" y2=\"1.241\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"8.609\" y1=\"0.501\" x2=\"8.609\" y2=\"7.5\"><\/line><\/svg>\n                <\/span> \n                 \n\n    <\/a>\n<\/div>\n        <\/div>\n    <\/div>\n\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a13536c layouts-column-align-inherit layouts-section-position-none elementor-invisible\" data-id=\"a13536c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-554b01d elementor-widget elementor-widget-iqonic_price\" data-id=\"554b01d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n    <div  class=\"iq-price-container iq-price-table-4  text-center iq-box-shadow active iq-box-shadow\">\n        <div class=\"iq-price-header\">  \n\n            <span class=\"iq-price-label\">e-HRM + reloj electr\u00f3nico<\/span>\n\n            <p class=\"iq-price-description\">Sistema de gesti\u00f3n de recursos humanos con reconocimiento facial<\/p> \n         \n        <\/div>\n\n        <div class=\"sub-header-main\">\n                            <span class=\"plan-offer\">Paquete con descuento<\/span>\n                \n            <div class=\"iq-price-sub-header\">\n                <h4 class=\"iq-price\">\n                    <small>&#36;<\/small>14                    <span class=\"iq-price-desc\">USD\/User                    <\/span>\n                <\/h4>\n                                    <p><p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignnone size-medium wp-image-26747\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2023\/01\/ehrmeclock.png?resize=300%2C234&#038;ssl=1\" alt=\"\" width=\"300\" height=\"234\" srcset=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2023\/01\/ehrmeclock.png?w=447&amp;ssl=1 447w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2023\/01\/ehrmeclock.png?resize=300%2C234&amp;ssl=1 300w\" sizes=\"auto, (min-width: 960px) 75vw, 100vw\" \/><\/p><\/p>\n                            <\/div>\n            \n        <\/div>\n\n        <div class=\"iq-price-body\">\n            <ul class=\"iq-price-service\">\n                                       <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Dashboard<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Employee Database<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>HR Administration<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Attendance &amp; Leaves<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>                        <span>Face Recognition<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>                        <span>Geo rencing restriction<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Project Management<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Timeesheet<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Multi-Company<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>HR Reports<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Payroll<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Appraisal<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Recruitment<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Custody<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Disciplinary Tracking<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>HR Reminder<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Legal Action<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Employee Checklist<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Resignation<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Employee Survey<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Gesti\u00f3n de vacaciones<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Anuncios de recursos humanos<\/span> \n                    <\/li>\n                      \n            <\/ul>\n        <\/div>\n\n        <div class=\"iq-price-footer\">\n             <div class=\"iq-btn-container\" >\n\n     <a class=\"iq-button-animated has-icon btn-icon-right\" href=\"https:\/\/ecloud.solutions\/es\/ehrm\/\" >  \n          \n                <span class=\"btn_text-main\"> \n                    <span class=\"btn_text one\">Purchase Now <\/span>\n                    <span class=\"btn_text two\">Purchase Now <\/span>\n                <\/span>                 <span class=\"btn-icon\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"10px\" height=\"10px\" viewbox=\"0 0 10 10\" enable-background=\"new 0 0 10 10\" xml:space=\"preserve\"><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"6.052\" y1=\"3.933\" x2=\"0.953\" y2=\"9.031\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"2.312\" y1=\"1.241\" x2=\"9.313\" y2=\"1.241\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"8.609\" y1=\"0.501\" x2=\"8.609\" y2=\"7.5\"><\/line><\/svg>\n                <\/span> \n                 \n\n    <\/a>\n<\/div>\n        <\/div>\n    <\/div>\n\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7803ec5f layouts-column-align-inherit layouts-section-position-none elementor-invisible\" data-id=\"7803ec5f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-5f2a31d2 elementor-widget elementor-widget-iqonic_price\" data-id=\"5f2a31d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n    <div  class=\"iq-price-container iq-price-table-4  text-center iq-box-shadow\">\n        <div class=\"iq-price-header\">  \n\n            <span class=\"iq-price-label\">e-Todo en uno<\/span>\n\n            <p class=\"iq-price-description\">Sistema Todo en Uno - ERP<\/p> \n         \n        <\/div>\n\n        <div class=\"sub-header-main\">\n            \n            <div class=\"iq-price-sub-header\">\n                <h4 class=\"iq-price\">\n                    <small>&#36;<\/small>Ask                    <span class=\"iq-price-desc\">USD\/User                    <\/span>\n                <\/h4>\n                                    <p><p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignnone size-medium wp-image-26749\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2023\/01\/AiO.png?resize=300%2C269&#038;ssl=1\" alt=\"\" width=\"300\" height=\"269\" srcset=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2023\/01\/AiO.png?w=410&amp;ssl=1 410w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2023\/01\/AiO.png?resize=300%2C269&amp;ssl=1 300w\" sizes=\"auto, (min-width: 960px) 75vw, 100vw\" \/><\/p><\/p>\n                            <\/div>\n            \n        <\/div>\n\n        <div class=\"iq-price-body\">\n            <ul class=\"iq-price-service\">\n                                       <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Sales<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Finance<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Human Resource Management<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Marketing<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Productivity<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Document Management System - DMS<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Project Management<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Servicios<\/span> \n                    <\/li>\n                                         <li class=\"active\">\n                          <i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>                        <span>Websites<\/span> \n                    <\/li>\n                      \n            <\/ul>\n        <\/div>\n\n        <div class=\"iq-price-footer\">\n             <div class=\"iq-btn-container\" >\n\n     <a class=\"iq-button-animated has-icon btn-icon-right\" href=\"https:\/\/ecloud.solutions\/es\/ehrm\/\" >  \n          \n                <span class=\"btn_text-main\"> \n                    <span class=\"btn_text one\">Purchase Now <\/span>\n                    <span class=\"btn_text two\">Purchase Now <\/span>\n                <\/span>                 <span class=\"btn-icon\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"10px\" height=\"10px\" viewbox=\"0 0 10 10\" enable-background=\"new 0 0 10 10\" xml:space=\"preserve\"><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"6.052\" y1=\"3.933\" x2=\"0.953\" y2=\"9.031\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"2.312\" y1=\"1.241\" x2=\"9.313\" y2=\"1.241\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"8.609\" y1=\"0.501\" x2=\"8.609\" y2=\"7.5\"><\/line><\/svg>\n                <\/span> \n                 \n\n    <\/a>\n<\/div>\n        <\/div>\n    <\/div>\n\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-2cbc3bc elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2cbc3bc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca4e6bf layouts-column-align-inherit layouts-section-position-none\" data-id=\"ca4e6bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-c40a964 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c40a964\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-77e032f layouts-column-align-inherit layouts-section-position-none\" data-id=\"77e032f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-459d91e elementor-widget elementor-widget-section_title\" data-id=\"459d91e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"center iq-title-box iq-title-default iq-title-box-1\">\n\t\t<div class=\"iq-title-icon\">\n\t\t\t\t\t<\/div>\n\t\t\t<span class=\"iq-subtitle iq-title-box-1\">our solutions<\/span>\t\t<h2 class=\"iq-title\" >\n\t\t\t\u00bfC\u00f3mo podemos ayudar?\t\t<\/h2>\n\t\t\t<p class=\"iq-title-desc\">regalanos unos minutos de tu tiempo, no nos interesa venderte nada, solo nos gustaria conocerte<\/p>\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-41cd60e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41cd60e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d187a5a layouts-column-align-inherit layouts-section-position-none elementor-invisible\" data-id=\"d187a5a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-fea462d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"fea462d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/ecloud.solutions\/es\/ehrm\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"339\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/eHR.png?fit=339%2C339&amp;ssl=1\" class=\"attachment-large size-large wp-image-26625\" alt=\"eHRM - Human Resource Management\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/ecloud.solutions\/es\/ehrm\/\">E-HRM<\/a><\/h3><p class=\"elementor-image-box-description\">Sistemas de telefon\u00eda en la nube - Voz en la Nube <br> -<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-e4a8939 elementor-widget elementor-widget-toggle\" data-id=\"e4a8939\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2391\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2391\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Panel de recursos humanos<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2391\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2391\"><p>Mantenga sus ojos en todo su an\u00e1lisis.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2392\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2392\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Interactivo y Web responsive<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2392\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2392\"><p>Todos tus empleados pueden interactuar entre s\u00ed, formando grupos de trabajo, tambi\u00e9n pueden usar la soluci\u00f3n sin instalaci\u00f3n y desde dispositivos m\u00f3viles o de escritorio<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2393\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2393\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gesti\u00f3n de turnos<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2393\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2393\"><p>Crear y administrar los turnos de trabajo de los empleados.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2394\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2394\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Recordatorios de empleados<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2394\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2394\"><p>Recordatorio establece alarma para recordar todas las fechas importantes. El s\u00edmbolo de &#039;Campana&#039; al lado del \u00edcono de chat har\u00e1 que aparezca su recordatorio. Puede configurar recordatorios para cualquier modelo (p. ej.: Ventas, Recursos Humanos, Proyecto, etc.) y tambi\u00e9n sus campos de fecha correspondientes para comparar. Facilita a la empresa memorizar las fechas especiales.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2395\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2395\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Planes y estrategias de evaluaci\u00f3n<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2395\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2395\"><p>Utilice lo mejor de su grupo de recursos humanos. Implemente estrategias de evaluaci\u00f3n para mantener alto el nivel de motivaci\u00f3n y desempe\u00f1o de sus empleados. Asegura planes de evaluaci\u00f3n de arriba hacia abajo y de abajo hacia arriba y brinda retroalimentaci\u00f3n oportuna y complementos para los logros.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2396\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2396\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gesti\u00f3n de demandas judiciales<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2396\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2396\"><p>Gestiona acciones judiciales y sus informes.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2397\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2397\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Lista de verificaci\u00f3n de entrada y salida<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2397\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2397\"><p>Una persona debe someterse a todos los elementos de la lista de verificaci\u00f3n configurada antes de ser admitida\/renunciada. El porcentaje correspondiente se mostrar\u00e1 en la vista de formulario de empleado.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2398\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2398\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Custodia\/Administraci\u00f3n de la propiedad<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2398\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2398\"><p>Gestiona el proceso de gesti\u00f3n de la custodia de los activos de la empresa, como port\u00e1tiles, c\u00e1maras, dispositivos, etc. Opci\u00f3n para renovar las solicitudes y tomar los informes...<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2399\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-2399\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">RRHH Multi Empresa<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2399\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-2399\"><p>Administre m\u00faltiples empleados de sucursal f\u00e1cilmente.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23910\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-23910\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Reconocimiento biom\u00e9trico<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23910\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-23910\"><p>Puede integrar dispositivos biom\u00e9tricos o incluso integrar la soluci\u00f3n E-Clock en la que no requiere dispositivos biom\u00e9tricos, en un tel\u00e9fono celular con c\u00e1mara o PC puede registrar la asistencia.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23911\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-23911\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Anuncios de recursos humanos<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23911\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-23911\"><p>Gesti\u00f3n de Anuncios Oficiales, Saludos, Advertencias, Recompensas, etc.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23912\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-23912\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gesti\u00f3n de vacaciones<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23912\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-23912\"><p>Ampliaci\u00f3n de la gesti\u00f3n de vacaciones con caracter\u00edsticas adicionales adaptables para gestionar las vacaciones de los empleados.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23913\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-23913\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gesti\u00f3n de documentos de recursos humanos<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23913\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-23913\"><p>Documentos en formulario de empleado con campos avanzados en formulario de empleado. Como datos familiares, fecha de incorporaci\u00f3n, fecha de caducidad del pasaporte y DNI con sus notificaciones de caducidad.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23914\" class=\"elementor-tab-title\" data-tab=\"14\" role=\"button\" aria-controls=\"elementor-tab-content-23914\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">portal de reclutamiento<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23914\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"14\" role=\"region\" aria-labelledby=\"elementor-tab-title-23914\"><p>Puede gestionar el proceso de selecci\u00f3n de forma p\u00fablica o privada, registr\u00e1ndose desde el proceso de solicitud, aprobaci\u00f3n, entrevistas, selecci\u00f3n, firma de contrato e incorporaci\u00f3n.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-cdd25fa elementor-button-info elementor-widget elementor-widget-button\" data-id=\"cdd25fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ecloud.solutions\/es\/ehrm\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Saber m\u00e1s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-143a5e7 layouts-column-align-inherit layouts-section-position-none elementor-invisible\" data-id=\"143a5e7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-a7c38af elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a7c38af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/ecloud.solutions\/es\/eclock\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"311\" height=\"311\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/ECLOCK.png?fit=311%2C311&amp;ssl=1\" class=\"attachment-large size-large wp-image-26559\" alt=\"eClock\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/ecloud.solutions\/es\/eclock\/\">reloj electronico<\/a><\/h3><p class=\"elementor-image-box-description\">Control de asistencia con reconocimiento facial\n <br> -<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-43ed49e elementor-widget elementor-widget-toggle\" data-id=\"43ed49e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7121\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-7121\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Internet 100%<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7121\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-7121\"><p>No requiere instalaci\u00f3n en PC o celular, garantiza la privacidad de tus empleados.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7122\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-7122\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">No se requiere hardware especial<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7122\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-7122\"><p>No te limites al hardware o su obsolescencia tecnol\u00f3gica, cualquier celular o PC puede funcionar<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7123\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-7123\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Modo Quiosco<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7123\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-7123\"><p>El modo quiosco est\u00e1 disponible para cualquier usuario con el permiso correspondiente sin licencias ni costes adicionales<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7124\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-7124\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Valla geogr\u00e1fica<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7124\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-7124\"><p>Puede restringir el acceso a los registros de asistencia a un \u00e1rea espec\u00edfica en un mapa usando el GPS del dispositivo.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7125\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-7125\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Seguimiento del tiempo del proyecto y parte de horas<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7125\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-7125\"><p>Cree proyectos y tareas asociadas y permita asignar tiempos a estas tareas para el control y seguimiento de las hojas de tiempo.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7126\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-7126\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gesti\u00f3n de empleados<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7126\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-7126\"><p>Gestiona a cada uno de tus empleados incluyendo toda la informaci\u00f3n personal, familiar, laboral, documentos personales, etc.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7127\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-7127\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Portal de autoservicio<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7127\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-7127\"><p>Permite acceder a la informaci\u00f3n del mismo empleado, como sus registros de entrada y salida, solicitud de licencias, entre otros.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7128\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-7128\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gesti\u00f3n de recepci\u00f3n<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7128\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-7128\"><p>Controle qui\u00e9n y cu\u00e1ndo personal externo a la organizaci\u00f3n accede a sus instalaciones<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7129\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-7129\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Integraci\u00f3n<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7129\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-7129\"><p>Si tiene Active Directory en su organizaci\u00f3n, int\u00e9grelo o integre otras soluciones que ya tenga implementadas.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-71210\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-71210\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Tablero e informes<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-71210\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-71210\"><p>Integre tableros e informes en l\u00ednea que faciliten compartir informaci\u00f3n entre \u00e1reas de la empresa al instante.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-39bcbdb elementor-button-info elementor-widget elementor-widget-button\" data-id=\"39bcbdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ecloud.solutions\/es\/eclock\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Saber m\u00e1s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a678c9b layouts-column-align-inherit layouts-section-position-none elementor-invisible\" data-id=\"a678c9b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-cc14dca elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"cc14dca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/ecloud.solutions\/es\/eucm\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"369\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/voice-in-cloud.png?fit=369%2C369&amp;ssl=1\" class=\"attachment-large size-large wp-image-26561\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/ecloud.solutions\/es\/eucm\/\">E-UCM<\/a><\/h3><p class=\"elementor-image-box-description\">Sistemas de telefon\u00eda en la nube - Voz en la Nube <br> -<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-24fbda9 elementor-widget elementor-widget-toggle\" data-id=\"24fbda9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3871\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3871\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Funciones b\u00e1sicas de la centralita<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3871\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3871\"><p>Obt\u00e9n tu extensi\u00f3n en aplicaciones windows, android o ios y realiza o recibe llamadas desde cualquier parte del mundo con recepcionista digital, directorio telef\u00f3nico entre otras funcionalidades b\u00e1sicas.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3872\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-3872\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Videoconferencia<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3872\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-3872\"><p>Enlaces para reuniones din\u00e1micas y est\u00e1ticas, encuestas, pantalla compartida, asistencia remota y pizarra.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3873\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-3873\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Chat en vivo y mensajer\u00eda<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3873\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-3873\"><p>integre canales de chat en vivo, WhatsApp, SMS y reportes de comunicaci\u00f3n de dichos canales.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3874\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-3874\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Caracter\u00edsticas del centro de llamadas<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3874\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-3874\"><p>Las funcionalidades de colas de llamadas, grabaciones, niveles de servicio, tablero, reporte de llamadas e integraci\u00f3n con CRM son parte de las funcionalidades b\u00e1sicas.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3875\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-3875\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Caracter\u00edsticas avanzadas<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3875\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-3875\"><p>Puede dise\u00f1ar su propio dise\u00f1ador de flujo de llamadas, hacer uso de Hot Desking, conectar oficinas remotas (puentes), enrutamiento basado en habilidades, iniciar \/ detener derechos de grabaci\u00f3n de llamadas. Logotipo de tel\u00e9fono IP personalizado, entre otros.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-164a05f elementor-button-warning elementor-widget elementor-widget-button\" data-id=\"164a05f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ecloud.solutions\/es\/eucm\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">saber m\u00e1s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-4e3a84f elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e3a84f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ce08c32 layouts-column-align-inherit layouts-section-position-none elementor-invisible\" data-id=\"ce08c32\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-c2074c8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c2074c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"409\" height=\"311\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/ECLOCK.png?fit=409%2C311&amp;ssl=1\" class=\"attachment-full size-full wp-image-26559\" alt=\"eClock\" srcset=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/ECLOCK.png?w=409&amp;ssl=1 409w, https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/ECLOCK.png?resize=300%2C228&amp;ssl=1 300w\" sizes=\"auto, (min-width: 960px) 75vw, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">reloj electronico<\/h3><p class=\"elementor-image-box-description\">Control de asistencia con reconocimiento facial\n <br> -<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-4c70a28 elementor-widget elementor-widget-toggle\" data-id=\"4c70a28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8011\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8011\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Internet 100%<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8011\"><p>No requiere instalaci\u00f3n en PC o celular, garantiza la privacidad de tus empleados.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8012\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-8012\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">No se requiere hardware especial<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8012\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-8012\"><p>No te limites al hardware o su obsolescencia tecnol\u00f3gica, cualquier celular o PC puede funcionar<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8013\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-8013\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Modo Quiosco<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8013\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-8013\"><p>El modo quiosco est\u00e1 disponible para cualquier usuario con el permiso correspondiente sin licencias ni costes adicionales<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8014\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-8014\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Valla geogr\u00e1fica<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8014\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-8014\"><p>Puede restringir el acceso a los registros de asistencia a un \u00e1rea espec\u00edfica en un mapa usando el GPS del dispositivo.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8015\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-8015\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Seguimiento del tiempo del proyecto y parte de horas<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8015\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-8015\"><p>Cree proyectos y tareas asociadas y permita asignar tiempos a estas tareas para el control y seguimiento de las hojas de tiempo.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8016\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-8016\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gesti\u00f3n de empleados<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8016\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-8016\"><p>Gestiona a cada uno de tus empleados incluyendo toda la informaci\u00f3n personal, familiar, laboral, documentos personales, etc.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8017\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-8017\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Portal de autoservicio<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8017\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-8017\"><p>Permite acceder a la informaci\u00f3n del mismo empleado, como sus registros de entrada y salida, solicitud de licencias, entre otros.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8018\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-8018\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gesti\u00f3n de recepci\u00f3n<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8018\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-8018\"><p>Controle qui\u00e9n y cu\u00e1ndo personal externo a la organizaci\u00f3n accede a sus instalaciones<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8019\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-8019\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Integraci\u00f3n<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8019\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-8019\"><p>Si tiene Active Directory en su organizaci\u00f3n, int\u00e9grelo o integre otras soluciones que ya tenga implementadas.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-80110\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-80110\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Tablero e informes<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-80110\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-80110\"><p>Integre tableros e informes en l\u00ednea que faciliten compartir informaci\u00f3n entre \u00e1reas de la empresa al instante.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-671aef4 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"671aef4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06ea197 layouts-column-align-inherit layouts-section-position-none\" data-id=\"06ea197\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-f30f3d2 elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"f30f3d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/pattern-4.png?fit=688%2C688&amp;ssl=1\" title=\"patr\u00f3n-4\" alt=\"image\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-7bfe6d1 elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"7bfe6d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/pattern-4.png?fit=688%2C688&amp;ssl=1\" title=\"patr\u00f3n-4\" alt=\"image\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-b64fc67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b64fc67\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3456b1f layouts-column-align-inherit layouts-section-position-none\" data-id=\"3456b1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1f952d3 layouts-column-align-inherit layouts-section-position-none\" data-id=\"1f952d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-580100e elementor-widget elementor-widget-section_title\" data-id=\"580100e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"center iq-title-box iq-title-default iq-title-box-1\">\n\t\t<div class=\"iq-title-icon\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<h2 class=\"iq-title\" >\n\t\t\tObt\u00e9n una hora de consultor\u00eda gratis\t\t<\/h2>\n\t\t\t<p class=\"iq-title-desc\">Solo registra tus datos para tener el gusto de escucharte.<\/p>\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-64463c4 elementor-widget elementor-widget-iq_button\" data-id=\"64463c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iq_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t <div class=\"iq-btn-container\" >\n\n     <a class=\"iq-button-animated has-icon btn-icon-right\" href=\"https:\/\/ecloud.solutions\/es\/contact-us-1\/\" >  \n          \n                <span class=\"btn_text-main\"> \n                    <span class=\"btn_text one\">Leer m\u00e1s <\/span>\n                    <span class=\"btn_text two\">Leer m\u00e1s <\/span>\n                <\/span>                 <span class=\"btn-icon\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"10px\" height=\"10px\" viewbox=\"0 0 10 10\" enable-background=\"new 0 0 10 10\" xml:space=\"preserve\"><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"6.052\" y1=\"3.933\" x2=\"0.953\" y2=\"9.031\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"2.312\" y1=\"1.241\" x2=\"9.313\" y2=\"1.241\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"8.609\" y1=\"0.501\" x2=\"8.609\" y2=\"7.5\"><\/line><\/svg>\n                <\/span> \n                 \n\n    <\/a>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-267d383 layouts-column-align-inherit layouts-section-position-none\" data-id=\"267d383\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-fdd2f37 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdd2f37\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-86b1dcb layouts-column-align-inherit layouts-section-position-none\" data-id=\"86b1dcb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-23fc10b elementor-widget elementor-widget-image\" data-id=\"23fc10b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/06\/Rectangle-2158.webp?fit=1397%2C573&amp;ssl=1\" title=\"Rect\u00e1ngulo-2158\" alt=\"image\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-69381168 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69381168\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d2fe75d layouts-column-align-inherit layouts-section-position-none\" data-id=\"7d2fe75d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-11ee987a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11ee987a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-610f6e82 layouts-column-align-inherit layouts-section-position-none\" data-id=\"610f6e82\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-70004090 elementor-widget elementor-widget-section_title\" data-id=\"70004090\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"center iq-title-box iq-title-default iq-title-box-1\">\n\t\t<div class=\"iq-title-icon\">\n\t\t\t\t\t<\/div>\n\t\t\t<span class=\"iq-subtitle iq-title-box-1\">other features<\/span>\t\t<h2 class=\"iq-title\" >\n\t\t\tNuestros diferenciadores clave\t\t<\/h2>\n\t\t\t\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-1c8d0dd0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c8d0dd0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-33dfd712 layouts-column-align-inherit layouts-section-position-none\" data-id=\"33dfd712\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-364f9df8 elementor-widget elementor-widget-iqonic_icon_box\" data-id=\"364f9df8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"iq-icon-box iq-icon-box-style-2\">\n\t\n\t<div class=\"icon-box-img\">\n\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/6.png?ssl=1\" title=\"6\" alt=\"image\" loading=\"lazy\" \/>\t<\/div>\n\t\t\t\n\t<div class=\"icon-box-content\">\n\t\t\t\t<h5 class=\"icon-box-title\"> <a >Escalabilidad<\/a>\n\t\t<\/h5>\t\n\t\t\t\t\t\t\n\t\t            <p class=\"icon-box-desc\"> Una soluci\u00f3n basada en la nube permite escalar f\u00e1cilmente a medida que su organizaci\u00f3n crece o cambia, proporcionando una plataforma flexible y adaptable para satisfacer sus necesidades. <\/p>\n                 \t<\/div>\n\t\n <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-68d24c95 layouts-column-align-inherit layouts-section-position-none\" data-id=\"68d24c95\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-4ac30312 elementor-widget elementor-widget-iqonic_icon_box\" data-id=\"4ac30312\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"iq-icon-box iq-icon-box-style-2\">\n\t\n\t<div class=\"icon-box-img\">\n\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/2.png?ssl=1\" title=\"2\" alt=\"image\" loading=\"lazy\" \/>\t<\/div>\n\t\t\t\n\t<div class=\"icon-box-content\">\n\t\t\t\t<h5 class=\"icon-box-title\"> <a >Accesibilidad<\/a>\n\t\t<\/h5>\t\n\t\t\t\t\t\t\n\t\t            <p class=\"icon-box-desc\"> La plataforma basada en la nube permite el acceso remoto desde cualquier lugar con conexi\u00f3n a Internet, lo que brinda flexibilidad tanto para los empleados como para el personal de recursos humanos. <\/p>\n                 \t<\/div>\n\t\n <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c16edce layouts-column-align-inherit layouts-section-position-none\" data-id=\"c16edce\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-430a691d elementor-widget elementor-widget-iqonic_icon_box\" data-id=\"430a691d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"iq-icon-box iq-icon-box-style-2\">\n\t\n\t<div class=\"icon-box-img\">\n\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/4.png?ssl=1\" title=\"4\" alt=\"image\" loading=\"lazy\" \/>\t<\/div>\n\t\t\t\n\t<div class=\"icon-box-content\">\n\t\t\t\t<h5 class=\"icon-box-title\"> <a >Colaboraci\u00f3n<\/a>\n\t\t<\/h5>\t\n\t\t\t\t\t\t\n\t\t            <p class=\"icon-box-desc\"> La plataforma admite la colaboraci\u00f3n entre el personal de recursos humanos, los empleados y los gerentes, lo que permite una comunicaci\u00f3n y un trabajo en equipo eficientes. <\/p>\n                 \t<\/div>\n\t\n <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-7cc0ece2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cc0ece2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-66b185b6 layouts-column-align-inherit layouts-section-position-none\" data-id=\"66b185b6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:0}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-656418aa elementor-widget elementor-widget-iqonic_icon_box\" data-id=\"656418aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"iq-icon-box iq-icon-box-style-2\">\n\t\n\t<div class=\"icon-box-img\">\n\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/5.png?ssl=1\" title=\"5\" alt=\"image\" loading=\"lazy\" \/>\t<\/div>\n\t\t\t\n\t<div class=\"icon-box-content\">\n\t\t\t\t<h5 class=\"icon-box-title\"> <a >Automatizaci\u00f3n<\/a>\n\t\t<\/h5>\t\n\t\t\t\t\t\t\n\t\t            <p class=\"icon-box-desc\"> El sistema automatiza muchos procesos de recursos humanos, como la incorporaci\u00f3n, la inscripci\u00f3n de beneficios y el seguimiento del tiempo libre, lo que reduce el esfuerzo manual y aumenta la precisi\u00f3n. <\/p>\n                 \t<\/div>\n\t\n <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5ce51b40 layouts-column-align-inherit layouts-section-position-none\" data-id=\"5ce51b40\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-24595255 elementor-widget elementor-widget-iqonic_icon_box\" data-id=\"24595255\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"iq-icon-box iq-icon-box-style-2\">\n\t\n\t<div class=\"icon-box-img\">\n\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/3.png?ssl=1\" title=\"3\" alt=\"image\" loading=\"lazy\" \/>\t<\/div>\n\t\t\t\n\t<div class=\"icon-box-content\">\n\t\t\t\t<h5 class=\"icon-box-title\"> <a >personalizaci\u00f3n<\/a>\n\t\t<\/h5>\t\n\t\t\t\t\t\t\n\t\t            <p class=\"icon-box-desc\"> Nuestra soluci\u00f3n basada en la nube ofrece amplias opciones de personalizaci\u00f3n para satisfacer las necesidades \u00fanicas de su organizaci\u00f3n, lo que permite una experiencia personalizada adecuada para su empresa. <\/p>\n                 \t<\/div>\n\t\n <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2d3b9a0 layouts-column-align-inherit layouts-section-position-none\" data-id=\"2d3b9a0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-74daffa1 elementor-widget elementor-widget-iqonic_icon_box\" data-id=\"74daffa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"iq-icon-box iq-icon-box-style-2\">\n\t\n\t<div class=\"icon-box-img\">\n\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/1.png?ssl=1\" title=\"1\" alt=\"image\" loading=\"lazy\" \/>\t<\/div>\n\t\t\t\n\t<div class=\"icon-box-content\">\n\t\t\t\t<h5 class=\"icon-box-title\"> <a >Seguridad<\/a>\n\t\t<\/h5>\t\n\t\t\t\t\t\t\n\t\t            <p class=\"icon-box-desc\"> La soluci\u00f3n e-HRM proporciona caracter\u00edsticas de seguridad s\u00f3lidas, que incluyen cifrado de datos, controles de acceso y centros de datos seguros, lo que garantiza la confidencialidad e integridad de sus datos. <\/p>\n                 \t<\/div>\n\t\n <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-a6052d4 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"a6052d4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60b0ecd layouts-column-align-inherit layouts-section-position-none\" data-id=\"60b0ecd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-hide-on-laptop elementor-section elementor-inner-section elementor-element elementor-element-2e88b02 elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e88b02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7d23be6 layouts-column-align-inherit layouts-section-position-none\" data-id=\"7d23be6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-0adb422 elementor-widget elementor-widget-section_title\" data-id=\"0adb422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"center iq-title-box iq-title-default iq-title-box-1\">\n\t\t<div class=\"iq-title-icon\">\n\t\t\t\t\t<\/div>\n\t\t\t<span class=\"iq-subtitle iq-title-box-1\">our portfolio<\/span>\t\t<h2 class=\"iq-title\" >\n\t\t\tNuestro trabajo reciente para mostrar\t\t<\/h2>\n\t\t\t\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"hf-hide-on-laptop elementor-section elementor-inner-section elementor-element elementor-element-1dcd427 elementor-section-full_width elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"1dcd427\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-50b2089 layouts-column-align-inherit layouts-section-position-none\" data-id=\"50b2089\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-de42192 elementor-widget elementor-widget-portfolio_new\" data-id=\"de42192\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"portfolio_new.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t<div class=\"iq-portfolio-slider iq-portfolio-slider-one\">\n\t\t<div class=\"owl-carousel\" data-dots=\"true\" data-nav=\"false\" data-items=\"2\" data-items-laptop=\"2\" data-items-tab=\"2\" data-items-mobile=\"1\" data-items-mobile-sm=\"1\" data-autoplay=\"false\" data-center=\"1\" data-loop=\"true\" data-margin=\"100\">\n\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n\n   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"hf-hide-on-laptop elementor-section elementor-top-section elementor-element elementor-element-76163fa2 elementor-section-stretched elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76163fa2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62227328 layouts-column-align-inherit layouts-section-position-none\" data-id=\"62227328\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7c88d660 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c88d660\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6836b859 layouts-column-align-inherit layouts-section-position-none\" data-id=\"6836b859\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-25cb101 elementor-widget elementor-widget-iq_testimonial_slick\" data-id=\"25cb101\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iq_testimonial_slick.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div class=\"qloud-slick-testimonial center\">\r\n    <div class=\"slider-wrapper\">\r\n        <ul class=\"qloud-thumb\" data-items=\"3\" data-tablet=\"2\" data-mobile=\"1\" data-align=\"center\">\r\n                                <li class=\"type-image\">\r\n                        <div class=\"testimonial-slider-img\">\r\n                            <img decoding=\"async\" loading=\"lazy\" alt=\"image-testimonial\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/testi-icon-05.png?resize=125%2C30&ssl=1\" >\r\n                        <\/div>\r\n                    <\/li>\r\n                                            <li class=\"type-image\">\r\n                        <div class=\"testimonial-slider-img\">\r\n                            <img decoding=\"async\" loading=\"lazy\" alt=\"image-testimonial\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/testi-icon-03.png?resize=125%2C30&ssl=1\" >\r\n                        <\/div>\r\n                    <\/li>\r\n                                            <li class=\"type-image\">\r\n                        <div class=\"testimonial-slider-img\">\r\n                            <img decoding=\"async\" loading=\"lazy\" alt=\"image-testimonial\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/testi-icon-04.png?resize=125%2C30&ssl=1\" >\r\n                        <\/div>\r\n                    <\/li>\r\n                                            <li class=\"type-image\">\r\n                        <div class=\"testimonial-slider-img\">\r\n                            <img decoding=\"async\" loading=\"lazy\" alt=\"image-testimonial\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/testi-icon-02.png?resize=125%2C30&ssl=1\" >\r\n                        <\/div>\r\n                    <\/li>\r\n                                            <li class=\"type-image\">\r\n                        <div class=\"testimonial-slider-img\">\r\n                            <img decoding=\"async\" loading=\"lazy\" alt=\"image-testimonial\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2020\/02\/testi-icon-01.png?resize=125%2C30&ssl=1\" >\r\n                        <\/div>\r\n                    <\/li>\r\n                                            <li class=\"type-image\">\r\n                        <div class=\"testimonial-slider-img\">\r\n                            <img decoding=\"async\" loading=\"lazy\" alt=\"image-testimonial\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2020\/02\/testi-icon-07.png?resize=125%2C30&ssl=1\" >\r\n                        <\/div>\r\n                    <\/li>\r\n                                <\/ul>\r\n\r\n        <ul class=\"qloud-content\">\r\n                                <li class=\"type-image\">\r\n                        <div class=\"qloud-testimonial-content\">\r\n                            <div class=\"text-dec\">\r\n                                <p>La velocidad es crucial en el marketing. Cuantas m\u00e1s campa\u00f1as podamos armar, m\u00e1s p\u00e1ginas podremos crear, m\u00e1s grandes nos sentiremos y m\u00e1s puntos de contacto tendremos con los clientes.<\/p>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/li>\r\n                                           <li class=\"type-image\">\r\n                        <div class=\"qloud-testimonial-content\">\r\n                            <div class=\"text-dec\">\r\n                                <p>Simplemente texto ficticio de la industria de la impresi\u00f3n y la composici\u00f3n tipogr\u00e1fica. Lorem Ipsum ha sido el texto ficticio est\u00e1ndar de la industria desde el siglo XVI, cuando un impresor desconocido tom\u00f3 una galera.<\/p>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/li>\r\n                                           <li class=\"type-image\">\r\n                        <div class=\"qloud-testimonial-content\">\r\n                            <div class=\"text-dec\">\r\n                                <p>Simplemente texto ficticio de la industria de la impresi\u00f3n y la composici\u00f3n tipogr\u00e1fica. Lorem Ipsum ha sido el texto ficticio est\u00e1ndar de la industria desde el siglo XVI, cuando un impresor desconocido tom\u00f3 una galera.<\/p>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/li>\r\n                                           <li class=\"type-image\">\r\n                        <div class=\"qloud-testimonial-content\">\r\n                            <div class=\"text-dec\">\r\n                                <p>Texto ficticio de la industria de la imprenta y la composici\u00f3n tipogr\u00e1fica. Lorem Ipsum ha sido el texto ficticio est\u00e1ndar de la industria desde el siglo XVI, cuando era un desconocido.<\/p>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/li>\r\n                                           <li class=\"type-image\">\r\n                        <div class=\"qloud-testimonial-content\">\r\n                            <div class=\"text-dec\">\r\n                                <p>Texto de la industria de la imprenta y la composici\u00f3n tipogr\u00e1fica. Lorem Ipsum ha sido el texto ficticio est\u00e1ndar de la industria desde el siglo XVI, cuando un impresor desconocido tom\u00f3 una galer\u00eda.<\/p>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/li>\r\n                                           <li class=\"type-image\">\r\n                        <div class=\"qloud-testimonial-content\">\r\n                            <div class=\"text-dec\">\r\n                                <p>Ipsum es simplemente texto ficticio de la industria de la impresi\u00f3n y la composici\u00f3n tipogr\u00e1fica. Lorem Ipsum ha sido el texto ficticio est\u00e1ndar de la industria desde el siglo XVI, cuando era un impresor desconocido.<\/p>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/li>\r\n                               <\/ul>\r\n\r\n        <ul class=\"qloud-image\" data-dots=\"true\" data-items=\"5\" data-tablet=\"2\" data-mobile=\"1\">\r\n                                <li class=\"type-image\">\r\n                        <div class=\"wrapper\">\r\n                            <div class=\"iq-testimonial-avtar\">\r\n                                <img decoding=\"async\" loading=\"lazy\" alt=\"image-testimonial\" class=\"img-fluid center-block\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/Rectangle-1975-1.png?resize=140%2C140&#038;ssl=1\">\r\n                            <\/div>\r\n                            <div class=\"author-wrapper\">\r\n                                <h5 class=\"Author-title\">jason roger<\/h5>\r\n                                <span class=\"Author-designation\">Designer<\/span>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/li>\r\n                                            <li class=\"type-image\">\r\n                        <div class=\"wrapper\">\r\n                            <div class=\"iq-testimonial-avtar\">\r\n                                <img decoding=\"async\" loading=\"lazy\" alt=\"image-testimonial\" class=\"img-fluid center-block\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/Rectangle-1974-1.png?resize=140%2C140&#038;ssl=1\">\r\n                            <\/div>\r\n                            <div class=\"author-wrapper\">\r\n                                <h5 class=\"Author-title\">jennifer caminante<\/h5>\r\n                                <span class=\"Author-designation\">Designer<\/span>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/li>\r\n                                            <li class=\"type-image\">\r\n                        <div class=\"wrapper\">\r\n                            <div class=\"iq-testimonial-avtar\">\r\n                                <img decoding=\"async\" loading=\"lazy\" alt=\"image-testimonial\" class=\"img-fluid center-block\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/05\/Rectangle-1973-1.png?resize=140%2C140&#038;ssl=1\">\r\n                            <\/div>\r\n                            <div class=\"author-wrapper\">\r\n                                <h5 class=\"Author-title\">JD Escoc\u00e9s<\/h5>\r\n                                <span class=\"Author-designation\">Designer<\/span>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/li>\r\n                                            <li class=\"type-image\">\r\n                        <div class=\"wrapper\">\r\n                            <div class=\"iq-testimonial-avtar\">\r\n                                <img decoding=\"async\" loading=\"lazy\" alt=\"image-testimonial\" class=\"img-fluid center-block\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2020\/02\/Ellipse-435.png?resize=140%2C140&#038;ssl=1\">\r\n                            <\/div>\r\n                            <div class=\"author-wrapper\">\r\n                                <h5 class=\"Author-title\">Fitt Morgan<\/h5>\r\n                                <span class=\"Author-designation\">Designer<\/span>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/li>\r\n                                            <li class=\"type-image\">\r\n                        <div class=\"wrapper\">\r\n                            <div class=\"iq-testimonial-avtar\">\r\n                                <img decoding=\"async\" loading=\"lazy\" alt=\"image-testimonial\" class=\"img-fluid center-block\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2020\/02\/Ellipse-434.png?resize=140%2C140&#038;ssl=1\">\r\n                            <\/div>\r\n                            <div class=\"author-wrapper\">\r\n                                <h5 class=\"Author-title\">nik jordan<\/h5>\r\n                                <span class=\"Author-designation\">Designer<\/span>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/li>\r\n                                            <li class=\"type-image\">\r\n                        <div class=\"wrapper\">\r\n                            <div class=\"iq-testimonial-avtar\">\r\n                                <img decoding=\"async\" loading=\"lazy\" alt=\"image-testimonial\" class=\"img-fluid center-block\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2020\/02\/Rectangle-1972-1.png?resize=140%2C140&#038;ssl=1\">\r\n                            <\/div>\r\n                            <div class=\"author-wrapper\">\r\n                                <h5 class=\"Author-title\">julia cooper<\/h5>\r\n                                <span class=\"Author-designation\">Designer<\/span>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/li>\r\n                                <\/ul>\r\n\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-878f494 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"878f494\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2f4b50 layouts-column-align-inherit layouts-section-position-none\" data-id=\"b2f4b50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-fba5875 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fba5875\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-60e256f layouts-column-align-inherit layouts-section-position-none\" data-id=\"60e256f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-4467a6d elementor-widget elementor-widget-section_title\" data-id=\"4467a6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"left iq-title-box iq-title-default iq-title-box-1\">\n\t\t<div class=\"iq-title-icon\">\n\t\t\t\t\t<\/div>\n\t\t\t<span class=\"iq-subtitle iq-title-box-1\">worldwide location<\/span>\t\t<h2 class=\"iq-title\" >\n\t\t\tDespliegue localmente con alcance global\t\t<\/h2>\n\t\t\t\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d54dd99 layouts-column-align-inherit layouts-section-position-none\" data-id=\"d54dd99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-197e28c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"197e28c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e971b04 layouts-column-align-right layouts-column-laptop-align-right layouts-column-mobile-align-left layouts-section-position-none\" data-id=\"e971b04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-2d3432a elementor-widget__width-auto elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2d3432a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"83\" height=\"88\" viewbox=\"0 0 83 88\" fill=\"none\"><rect y=\"0.5\" width=\"83\" height=\"87\" rx=\"41.5\" fill=\"white\"><\/rect><path d=\"M34.3641 61.5V33.4919H25.7987V38.2294H29.3234V61.5H34.3641ZM55.5718 61.5V33.4919H47.0064V38.2294H50.5311V61.5H55.5718Z\" fill=\"#285BD4\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ed4fd32 layouts-column-align-inherit layouts-section-position-none\" data-id=\"ed4fd32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-801be88 elementor-widget__width-auto elementor-widget elementor-widget-section_title\" data-id=\"801be88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"left iq-title-box iq-title-default iq-title-box-1\">\n\t\t<div class=\"iq-title-icon\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<h5 class=\"iq-title\" >\n\t\t\t5 Ubicaci\u00f3n total\t\t<\/h5>\n\t\t\t<p class=\"iq-title-desc\">Canad\u00e1 \u2013 Vancouver \/ USA \u2013 Miami \/ Colombia \u2013 Bogot\u00e1 \/ Ecuador \u2013 Guayaquil \/ Espa\u00f1a \u2013 Madrid <\/p>\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e020411 elementor-hidden-tablet elementor-hidden-mobile layouts-column-align-inherit layouts-section-position-none\" data-id=\"e020411\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-35dc4d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35dc4d3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-70d7ec5 layouts-column-align-inherit layouts-section-position-none\" data-id=\"70d7ec5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-428262f elementor-widget elementor-widget-iqonic_tooltip\" data-id=\"428262f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_tooltip.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"iq-tooltip\">\n              <div class=\"iq-image-pointer elementor-repeater-item-bc19ba3\">\n            <div class=\"iq-tooltip-box\">\n                <span class=\"icon\">\n                    <i aria-hidden=\"true\" class=\"flaticon-flaticon flaticon-facebook-placeholder-for-locate-places-on-maps\"><\/i>                <\/span>\n                <div class=\"iq-tooltip-content\">\n                    <div class=\"iq-tooltip-inner\">\n                        <h4 class=\"title\">Canada<\/h4>                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n                <div class=\"iq-image-pointer elementor-repeater-item-0cd90b4\">\n            <div class=\"iq-tooltip-box\">\n                <span class=\"icon\">\n                    <i aria-hidden=\"true\" class=\"flaticon-flaticon flaticon-facebook-placeholder-for-locate-places-on-maps\"><\/i>                <\/span>\n                <div class=\"iq-tooltip-content\">\n                    <div class=\"iq-tooltip-inner\">\n                        <h4 class=\"title\">Unite States<\/h4>                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n                <div class=\"iq-image-pointer elementor-repeater-item-69bdd1c\">\n            <div class=\"iq-tooltip-box\">\n                <span class=\"icon\">\n                    <i aria-hidden=\"true\" class=\"flaticon-flaticon flaticon-facebook-placeholder-for-locate-places-on-maps\"><\/i>                <\/span>\n                <div class=\"iq-tooltip-content\">\n                    <div class=\"iq-tooltip-inner\">\n                        <h4 class=\"title\">Colombia<\/h4>                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n                <div class=\"iq-image-pointer elementor-repeater-item-7465ca7\">\n            <div class=\"iq-tooltip-box\">\n                <span class=\"icon\">\n                    <i aria-hidden=\"true\" class=\"flaticon-flaticon flaticon-facebook-placeholder-for-locate-places-on-maps\"><\/i>                <\/span>\n                <div class=\"iq-tooltip-content\">\n                    <div class=\"iq-tooltip-inner\">\n                        <h4 class=\"title\">Spain<\/h4>                        <p class=\"content\">it is a long established fact that a reader.<\/p>                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n                <div class=\"iq-image-pointer elementor-repeater-item-f7a9455\">\n            <div class=\"iq-tooltip-box\">\n                <span class=\"icon\">\n                    <i aria-hidden=\"true\" class=\"flaticon-flaticon flaticon-facebook-placeholder-for-locate-places-on-maps\"><\/i>                <\/span>\n                <div class=\"iq-tooltip-content\">\n                    <div class=\"iq-tooltip-inner\">\n                        <h4 class=\"title\">Ecuador<\/h4>                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-72698886 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72698886\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-496cf4de layouts-column-align-inherit layouts-section-position-none\" data-id=\"496cf4de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-346b1a48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"346b1a48\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-51d659bf layouts-column-align-inherit layouts-section-position-none\" data-id=\"51d659bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-22d759c8 elementor-widget elementor-widget-section_title\" data-id=\"22d759c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"center iq-title-box iq-title-default iq-title-box-1\">\n\t\t<div class=\"iq-title-icon\">\n\t\t\t\t\t<\/div>\n\t\t\t<span class=\"iq-subtitle iq-title-box-1\">Our post<\/span>\t\t<h2 class=\"iq-title\" >\n\t\t\tDe nuestro \u00faltimo blog\t\t<\/h2>\n\t\t\t\t<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-510ea5a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"510ea5a9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-570df6de layouts-column-align-inherit layouts-section-position-none\" data-id=\"570df6de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-dda7f3b elementor-widget elementor-widget-iqonic_blog\" data-id=\"dda7f3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iqonic_blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t   \n    <div class=\"iq-blog  iq-blog-two\">   \n      <div id=\"my-carousel\" class=\"blog-carousel owl-carousel\" data-dots=\"false\" data-nav=\"false\" data-items=\"3\" data-items-laptop=\"3\" data-items-tab=\"2\" data-items-mobile=\"1\" data-items-mobile-sm=\"1\" data-autoplay=\"false\" data-loop=\"true\" data-center=\"false\" data-margin=\"32\">             <div class=\"iq-blog-box\">\n              <div class=\"iq-blog-image\"> <img decoding=\"async\" loading=\"lazy\" alt=\"image\" src=\"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2020\/02\/blog-02.jpg?fit=1400%2C800&#038;ssl=1\"\/> \n                                    <ul class=\"iq-blog-category list-inline\"> <li><a href= \"https:\/\/ecloud.solutions\/es\/category\/cloud-data\/\" > Cloud &amp; Data <\/a><\/li>                    <\/ul>               <\/div>\n              <div class=\"iq-blog-detail\">\n                <div class=\"iq-blog-meta\">\n                  <ul class=\"list-inline\"> \n                    <li class=\"list-inline-item\">\n                      <a href=\"https:\/\/ecloud.solutions\/es\/author\/johnmartinflorez\/\" class=\"iq-user\">\n                        By   \n                        johnmartinflorez                       <\/a>\n                    <\/li> \n                    <li class=\"list-inline-item\">\n                      <span class=\"screen-reader-text\">Posted on<\/span> <a href=\"https:\/\/ecloud.solutions\/es\/2020\/02\/17\/\" rel=\"bookmark\"><time class=\"entry-date published updated\" datetime=\"2020-02-17T06:44:40+00:00\"> 17 febrero, 2020 <\/time><\/a>                    <\/li>\n                  <\/ul>\n                <\/div>\n                <div class=\"blog-title\">\n                  <a class=\"button-link\" href=\"https:\/\/ecloud.solutions\/es\/official-terraform-provider\/\">\n                    <h5>Official Terraform Provider<\/h5>\n                  <\/a>\n                <\/div>\n                                    <p> Es un hecho establecido desde hace mucho tiempo que un lector se distraer\u00e1 con lo legible.<\/p>\n                <div class=\"iq-btn-container\" >\n\n    <a class=\"btn-icon-right iq-button-animated linked-btn has_icon\" href=\"https:\/\/ecloud.solutions\/es\/official-terraform-provider\/\"   >\n         \n                <span class=\"btn_text-main\"> \n                    <span class=\"btn_text one\">Leer m\u00e1s <\/span>\n                    <span class=\"btn_text two\">Leer m\u00e1s <\/span>\n                <\/span>                 <span class=\"btn-icon\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"10px\" height=\"10px\" viewbox=\"0 0 10 10\" enable-background=\"new 0 0 10 10\" xml:space=\"preserve\"><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"6.052\" y1=\"3.933\" x2=\"0.953\" y2=\"9.031\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"2.312\" y1=\"1.241\" x2=\"9.313\" y2=\"1.241\"><\/line><line fill=\"none\" stroke=\"#fff\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" x1=\"8.609\" y1=\"0.501\" x2=\"8.609\" y2=\"7.5\"><\/line><\/svg>\n                <\/span> \n                 <\/a>\n<\/div>\n              <\/div>\n            <\/div>       <\/div> <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>e-hRMHuman Resources Management by eCloud how we can help? a complete solution for the effective management of your staff. A cloud solution that allows you to have everything in one place from anywhere. Web ResponsiveWork from any device Employee DashboardCheck his\/her CV, Docs, skills, contract, among others. TimesheetManage your activities &amp; workforce Keep your projects [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"nf_dc_page":"","content-type":"","om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-26632","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>eHRM - ecloud.solution<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecloud.solutions\/es\/ehrm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"eHRM - ecloud.solution\" \/>\n<meta property=\"og:description\" content=\"e-hRMHuman Resources Management by eCloud how we can help? a complete solution for the effective management of your staff. A cloud solution that allows you to have everything in one place from anywhere. Web ResponsiveWork from any device Employee DashboardCheck his\/her CV, Docs, skills, contract, among others. TimesheetManage your activities &amp; workforce Keep your projects [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecloud.solutions\/es\/ehrm\/\" \/>\n<meta property=\"og:site_name\" content=\"ecloud.solution\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-11T17:51:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/eHR-300x245.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"27 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecloud.solutions\\\/ehrm\\\/\",\"url\":\"https:\\\/\\\/ecloud.solutions\\\/ehrm\\\/\",\"name\":\"eHRM - ecloud.solution\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/box5225.temp.domains\\\/~wvvjdomy\\\/ecloud\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecloud.solutions\\\/ehrm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ecloud.solutions\\\/ehrm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecloud.solutions\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/eHR-300x245.png\",\"datePublished\":\"2022-12-25T23:26:01+00:00\",\"dateModified\":\"2023-03-11T17:51:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecloud.solutions\\\/ehrm\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecloud.solutions\\\/ehrm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/ecloud.solutions\\\/ehrm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecloud.solutions\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/eHR-300x245.png\",\"contentUrl\":\"https:\\\/\\\/ecloud.solutions\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/eHR-300x245.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecloud.solutions\\\/ehrm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecloud.solutions\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"eHRM\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/box5225.temp.domains\\\/~wvvjdomy\\\/ecloud\\\/#website\",\"url\":\"http:\\\/\\\/box5225.temp.domains\\\/~wvvjdomy\\\/ecloud\\\/\",\"name\":\"ecloud.solution\",\"description\":\"cloud at your fingertips\",\"publisher\":{\"@id\":\"http:\\\/\\\/box5225.temp.domains\\\/~wvvjdomy\\\/ecloud\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/box5225.temp.domains\\\/~wvvjdomy\\\/ecloud\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/box5225.temp.domains\\\/~wvvjdomy\\\/ecloud\\\/#organization\",\"name\":\"ecloud.solution\",\"url\":\"http:\\\/\\\/box5225.temp.domains\\\/~wvvjdomy\\\/ecloud\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"http:\\\/\\\/box5225.temp.domains\\\/~wvvjdomy\\\/ecloud\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/ecloud.solutions\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-ecloud-solutions-nube-blanca-para-fondo-oscuro.png?fit=409%2C380&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/ecloud.solutions\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-ecloud-solutions-nube-blanca-para-fondo-oscuro.png?fit=409%2C380&ssl=1\",\"width\":409,\"height\":380,\"caption\":\"ecloud.solution\"},\"image\":{\"@id\":\"http:\\\/\\\/box5225.temp.domains\\\/~wvvjdomy\\\/ecloud\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"eHRM - ecloud.solution","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecloud.solutions\/es\/ehrm\/","og_locale":"es_ES","og_type":"article","og_title":"eHRM - ecloud.solution","og_description":"e-hRMHuman Resources Management by eCloud how we can help? a complete solution for the effective management of your staff. A cloud solution that allows you to have everything in one place from anywhere. Web ResponsiveWork from any device Employee DashboardCheck his\/her CV, Docs, skills, contract, among others. TimesheetManage your activities &amp; workforce Keep your projects [&hellip;]","og_url":"https:\/\/ecloud.solutions\/es\/ehrm\/","og_site_name":"ecloud.solution","article_modified_time":"2023-03-11T17:51:19+00:00","og_image":[{"url":"https:\/\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/eHR-300x245.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"27 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecloud.solutions\/ehrm\/","url":"https:\/\/ecloud.solutions\/ehrm\/","name":"eHRM - ecloud.solution","isPartOf":{"@id":"http:\/\/box5225.temp.domains\/~wvvjdomy\/ecloud\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecloud.solutions\/ehrm\/#primaryimage"},"image":{"@id":"https:\/\/ecloud.solutions\/ehrm\/#primaryimage"},"thumbnailUrl":"https:\/\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/eHR-300x245.png","datePublished":"2022-12-25T23:26:01+00:00","dateModified":"2023-03-11T17:51:19+00:00","breadcrumb":{"@id":"https:\/\/ecloud.solutions\/ehrm\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecloud.solutions\/ehrm\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/ecloud.solutions\/ehrm\/#primaryimage","url":"https:\/\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/eHR-300x245.png","contentUrl":"https:\/\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/eHR-300x245.png"},{"@type":"BreadcrumbList","@id":"https:\/\/ecloud.solutions\/ehrm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecloud.solutions\/"},{"@type":"ListItem","position":2,"name":"eHRM"}]},{"@type":"WebSite","@id":"http:\/\/box5225.temp.domains\/~wvvjdomy\/ecloud\/#website","url":"http:\/\/box5225.temp.domains\/~wvvjdomy\/ecloud\/","name":"ecloud.solution","description":"cloud at your fingertips","publisher":{"@id":"http:\/\/box5225.temp.domains\/~wvvjdomy\/ecloud\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/box5225.temp.domains\/~wvvjdomy\/ecloud\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"http:\/\/box5225.temp.domains\/~wvvjdomy\/ecloud\/#organization","name":"ecloud.solution","url":"http:\/\/box5225.temp.domains\/~wvvjdomy\/ecloud\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"http:\/\/box5225.temp.domains\/~wvvjdomy\/ecloud\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/logo-ecloud-solutions-nube-blanca-para-fondo-oscuro.png?fit=409%2C380&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ecloud.solutions\/wp-content\/uploads\/2022\/12\/logo-ecloud-solutions-nube-blanca-para-fondo-oscuro.png?fit=409%2C380&ssl=1","width":409,"height":380,"caption":"ecloud.solution"},"image":{"@id":"http:\/\/box5225.temp.domains\/~wvvjdomy\/ecloud\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ecloud.solutions\/es\/wp-json\/wp\/v2\/pages\/26632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecloud.solutions\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecloud.solutions\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecloud.solutions\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecloud.solutions\/es\/wp-json\/wp\/v2\/comments?post=26632"}],"version-history":[{"count":20,"href":"https:\/\/ecloud.solutions\/es\/wp-json\/wp\/v2\/pages\/26632\/revisions"}],"predecessor-version":[{"id":27119,"href":"https:\/\/ecloud.solutions\/es\/wp-json\/wp\/v2\/pages\/26632\/revisions\/27119"}],"wp:attachment":[{"href":"https:\/\/ecloud.solutions\/es\/wp-json\/wp\/v2\/media?parent=26632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}